{"id":13648,"date":"2018-07-08T08:54:00","date_gmt":"2018-07-08T08:54:00","guid":{"rendered":"https:\/\/www.cfm.co.mz\/?p=13648"},"modified":"2025-07-08T08:56:46","modified_gmt":"2025-07-08T08:56:46","slug":"aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira","status":"publish","type":"post","link":"https:\/\/www.cfm.co.mz\/en\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/","title":{"rendered":"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para os portos da Beira, equipados de reservat\u00f3rios de \u00e1gua com capacidade de 4000 litros e tanque de espuma com capacidade de 200 litros, de modo a garantir de forma eficiente na resposta em caso de inc\u00eandios causados por combust\u00edveis manuseados no Porto bem nas proximidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Valor do Contrato: <\/strong>234.4 mil USD<br><strong>Financiador: <\/strong>CFM<br><strong>Cronograma <\/strong>:\u00a0 2018 <strong>&#8211; <\/strong>2019<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"815\" height=\"521\" src=\"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp\" alt=\"\" class=\"wp-image-13649\" srcset=\"https:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp 815w, https:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm-300x192.webp 300w, https:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm-768x491.webp 768w\" sizes=\"(max-width: 815px) 100vw, 815px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para os portos da Beira, equipados de reservat\u00f3rios de \u00e1gua com capacidade de 4000 litros e tanque de espuma com capacidade de 200 litros, de modo a garantir de forma eficiente na resposta em caso de inc\u00eandios causados por combust\u00edveis manuseados no Porto bem nas proximidades. Valor do Contrato: 234.4 mil USDFinanciador: CFMCronograma :\u00a0 2018 &#8211; 2019<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[755],"tags":[],"class_list":["post-13648","post","type-post","status-publish","format-standard","hentry","category-porto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira - CFM - Caminhos De Ferros de Mo\u00e7ambique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfm.co.mz\/en\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira - CFM - Caminhos De Ferros de Mo\u00e7ambique\" \/>\n<meta property=\"og:description\" content=\"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para os portos da Beira, equipados de reservat\u00f3rios de \u00e1gua com capacidade de 4000 litros e tanque de espuma com capacidade de 200 litros, de modo a garantir de forma eficiente na resposta em caso de inc\u00eandios causados por combust\u00edveis manuseados no Porto bem nas proximidades. Valor do Contrato: 234.4 mil USDFinanciador: CFMCronograma :\u00a0 2018 &#8211; 2019\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfm.co.mz\/en\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/\" \/>\n<meta property=\"og:site_name\" content=\"CFM - Caminhos De Ferros de Mo\u00e7ambique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CFMMoz\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-08T08:54:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T08:56:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.cfm.co.mz\/#\/schema\/person\/157840ba70f0ef9580e250f10590d7d3\"},\"headline\":\"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira\",\"datePublished\":\"2018-07-08T08:54:00+00:00\",\"dateModified\":\"2025-07-08T08:56:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/\"},\"wordCount\":79,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cfm.co.mz\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp\",\"articleSection\":[\"Portos CFM Centro\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/\",\"url\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/\",\"name\":\"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira - CFM - Caminhos De Ferros de Mo\u00e7ambique\",\"isPartOf\":{\"@id\":\"https:\/\/www.cfm.co.mz\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp\",\"datePublished\":\"2018-07-08T08:54:00+00:00\",\"dateModified\":\"2025-07-08T08:56:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#primaryimage\",\"url\":\"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp\",\"contentUrl\":\"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cfm.co.mz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cfm.co.mz\/#website\",\"url\":\"https:\/\/www.cfm.co.mz\/\",\"name\":\"CFM - Caminhos De Ferros de Mo\u00e7ambique\",\"description\":\"Ampliando Horizontes\",\"publisher\":{\"@id\":\"https:\/\/www.cfm.co.mz\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cfm.co.mz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cfm.co.mz\/#organization\",\"name\":\"CFM - Caminhos De Ferros de Mo\u00e7ambique\",\"url\":\"https:\/\/www.cfm.co.mz\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.cfm.co.mz\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/be5f0679-4f5b-4d02-9719-a26ceed29162.jpg\",\"contentUrl\":\"https:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/be5f0679-4f5b-4d02-9719-a26ceed29162.jpg\",\"width\":400,\"height\":65,\"caption\":\"CFM - Caminhos De Ferros de Mo\u00e7ambique\"},\"image\":{\"@id\":\"https:\/\/www.cfm.co.mz\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CFMMoz\",\"https:\/\/www.linkedin.com\/company\/caminhos-de-ferro-de-moambique\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cfm.co.mz\/#\/schema\/person\/157840ba70f0ef9580e250f10590d7d3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.cfm.co.mz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.cfm.co.mz\/wp-content\/litespeed\/avatar\/6fd0e3f342694c54b3609d1ca78366af.jpg?ver=1784108113\",\"contentUrl\":\"https:\/\/www.cfm.co.mz\/wp-content\/litespeed\/avatar\/6fd0e3f342694c54b3609d1ca78366af.jpg?ver=1784108113\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/www.cfm.co.mz\"],\"url\":\"https:\/\/www.cfm.co.mz\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira - CFM - Caminhos De Ferros de Mo\u00e7ambique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfm.co.mz\/en\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/","og_locale":"en_US","og_type":"article","og_title":"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira - CFM - Caminhos De Ferros de Mo\u00e7ambique","og_description":"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para os portos da Beira, equipados de reservat\u00f3rios de \u00e1gua com capacidade de 4000 litros e tanque de espuma com capacidade de 200 litros, de modo a garantir de forma eficiente na resposta em caso de inc\u00eandios causados por combust\u00edveis manuseados no Porto bem nas proximidades. Valor do Contrato: 234.4 mil USDFinanciador: CFMCronograma :\u00a0 2018 &#8211; 2019","og_url":"https:\/\/www.cfm.co.mz\/en\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/","og_site_name":"CFM - Caminhos De Ferros de Mo\u00e7ambique","article_publisher":"https:\/\/www.facebook.com\/CFMMoz","article_published_time":"2018-07-08T08:54:00+00:00","article_modified_time":"2025-07-08T08:56:46+00:00","og_image":[{"url":"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#article","isPartOf":{"@id":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/"},"author":{"name":"admin","@id":"https:\/\/www.cfm.co.mz\/#\/schema\/person\/157840ba70f0ef9580e250f10590d7d3"},"headline":"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira","datePublished":"2018-07-08T08:54:00+00:00","dateModified":"2025-07-08T08:56:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/"},"wordCount":79,"commentCount":0,"publisher":{"@id":"https:\/\/www.cfm.co.mz\/#organization"},"image":{"@id":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#primaryimage"},"thumbnailUrl":"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp","articleSection":["Portos CFM Centro"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/","url":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/","name":"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira - CFM - Caminhos De Ferros de Mo\u00e7ambique","isPartOf":{"@id":"https:\/\/www.cfm.co.mz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#primaryimage"},"image":{"@id":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#primaryimage"},"thumbnailUrl":"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp","datePublished":"2018-07-08T08:54:00+00:00","dateModified":"2025-07-08T08:56:46+00:00","breadcrumb":{"@id":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#primaryimage","url":"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp","contentUrl":"http:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/bombeiroscfm.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfm.co.mz\/2018\/07\/08\/aquisicao-de-viatura-de-combate-a-incendio-para-o-porto-da-beira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cfm.co.mz\/"},{"@type":"ListItem","position":2,"name":"Aquisi\u00e7\u00e3o de viatura de combate a inc\u00eandio para o porto da Beira"}]},{"@type":"WebSite","@id":"https:\/\/www.cfm.co.mz\/#website","url":"https:\/\/www.cfm.co.mz\/","name":"CFM - Caminhos De Ferros de Mo\u00e7ambique","description":"Ampliando Horizontes","publisher":{"@id":"https:\/\/www.cfm.co.mz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfm.co.mz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cfm.co.mz\/#organization","name":"CFM - Caminhos De Ferros de Mo\u00e7ambique","url":"https:\/\/www.cfm.co.mz\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cfm.co.mz\/#\/schema\/logo\/image\/","url":"https:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/be5f0679-4f5b-4d02-9719-a26ceed29162.jpg","contentUrl":"https:\/\/www.cfm.co.mz\/wp-content\/uploads\/2025\/07\/be5f0679-4f5b-4d02-9719-a26ceed29162.jpg","width":400,"height":65,"caption":"CFM - Caminhos De Ferros de Mo\u00e7ambique"},"image":{"@id":"https:\/\/www.cfm.co.mz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CFMMoz","https:\/\/www.linkedin.com\/company\/caminhos-de-ferro-de-moambique\/"]},{"@type":"Person","@id":"https:\/\/www.cfm.co.mz\/#\/schema\/person\/157840ba70f0ef9580e250f10590d7d3","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cfm.co.mz\/#\/schema\/person\/image\/","url":"https:\/\/www.cfm.co.mz\/wp-content\/litespeed\/avatar\/6fd0e3f342694c54b3609d1ca78366af.jpg?ver=1784108113","contentUrl":"https:\/\/www.cfm.co.mz\/wp-content\/litespeed\/avatar\/6fd0e3f342694c54b3609d1ca78366af.jpg?ver=1784108113","caption":"admin"},"sameAs":["http:\/\/www.cfm.co.mz"],"url":"https:\/\/www.cfm.co.mz\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cfm.co.mz\/en\/wp-json\/wp\/v2\/posts\/13648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfm.co.mz\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfm.co.mz\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfm.co.mz\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfm.co.mz\/en\/wp-json\/wp\/v2\/comments?post=13648"}],"version-history":[{"count":1,"href":"https:\/\/www.cfm.co.mz\/en\/wp-json\/wp\/v2\/posts\/13648\/revisions"}],"predecessor-version":[{"id":13650,"href":"https:\/\/www.cfm.co.mz\/en\/wp-json\/wp\/v2\/posts\/13648\/revisions\/13650"}],"wp:attachment":[{"href":"https:\/\/www.cfm.co.mz\/en\/wp-json\/wp\/v2\/media?parent=13648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfm.co.mz\/en\/wp-json\/wp\/v2\/categories?post=13648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfm.co.mz\/en\/wp-json\/wp\/v2\/tags?post=13648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}